{"id":107,"date":"2023-04-03T20:56:11","date_gmt":"2023-04-03T19:56:11","guid":{"rendered":"https:\/\/iicrabat.esteri.it\/lingua-e-cultura\/certificazioni\/"},"modified":"2026-08-25T13:05:15","modified_gmt":"2026-08-25T12:05:15","slug":"certificazioni","status":"publish","type":"page","link":"https:\/\/iicrabat.esteri.it\/fr\/lingua-e-cultura\/certificazioni\/","title":{"rendered":"Certifications"},"content":{"rendered":"<p><strong>Certification d\u2019Italien comme langue \u00e9trang\u00e8re<\/strong><\/p>\n<p>Les certifications de la langue Italienne sont des titres officiels qui attestent et certifient le niveau de la langue Italienne en tant que langue \u00e9trang\u00e8re selon les niveaux d\u00e9finis par le Cadre Europ\u00e9en Commune de R\u00e9f\u00e9rence pour les langues (<em>Common European Framework of Reference for Languages<\/em>).<\/p>\n<p>Ils sont destin\u00e9s \u00e0 tous les citoyens \u00e9trangers, aux italiens r\u00e9sident \u00e0 l\u2019\u00e9tranger (descendants d\u2019\u00e9migrants italiens) et aux \u00e9trangers r\u00e9sident en Italie. Pour pouvoir participer aux \u00e9preuves d\u2019examen, il n\u2019est pas requis un niveau d\u2019\u00e9tude sp\u00e9cifique.<\/p>\n<p>Les Instituts Culturels Italiens (IIC) effectuent une activit\u00e9 d\u2019administration des examens de certification de la comp\u00e9tence de langue Italienne, en collaboration avec les organismes certificateurs de la langue Italienne reconnus par le D.M. du 7 d\u00e9cembre 2021 du Minist\u00e8re de l\u2019Int\u00e9rieur : Societ\u00e0 Dante Alighieri, Universit\u00e0 per Stranieri di Perugia, Universit\u00e0 per Stranieri di Siena, Universit\u00e0 Roma Tre, Universit\u00e0 per Stranieri \u201cDante Alighieri\u201d di Reggio Calabria.<\/p>\n<p><strong>L\u2019Institut Culturel Italien de Rabat est si\u00e8ge officiel d\u2019examen pour l\u2019obtention du Certificat d\u2019Italien comme Langue Etrang\u00e8re (CILS) en accord avec l\u2019Universit\u00e9 pour \u00e9trangers de Sienne<\/strong>. L\u2019examen CILS se d\u00e9roule chaque ann\u00e9e dans les mois des juin et d\u00e9cembre aupr\u00e8s de l\u2019Institut.<\/p>\n<p>Les inscriptions doivent \u00eatre effectu\u00e9es au moins 40 jours \u00e0 l\u2019avance aupr\u00e8s de l\u2019Institut Culturel Italien \u2013<strong> tel. 0537 76 68 26\/47\u00a0 &#8211; Email: <\/strong><a href=\"mailto:amministrazione.iicrabat@esteri.it\"><strong>amministrazione.iicrabat@esteri.it<\/strong><\/a><\/p>\n<p>L\u2019horaire de r\u00e9ception du public pour l\u2019inscription \u00e0 la session d\u2019examen CILS est du lundi au jeudi du 10h00 \u00e0 15h00 et le vendredi du 10h00 \u00e0 13h00.<\/p>\n<p>Pour des informations plus d\u00e9taill\u00e9es, veuillez consulter le site\u00a0: <a href=\"https:\/\/cils.unistrasi.it\/1\/98\/Esami_CILS.htm\">https:\/\/cils.unistrasi.it\/1\/98\/Esami_CILS.htm<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Examen CILS \u2013 Certification d\u2019Italien comme Langue Etrang\u00e8re d\u00e9livr\u00e9e par l\u2019Universit\u00e9 pour \u00e9trangers de Sienne<\/strong><\/p>\n<p><strong>Prochaines sessions: <\/strong><\/p>\n<p><strong>Session: 03\/12\/2026 dont il est possible inscrire les candidats jusqu\u2019\u00e0 23 :59 du 24 octobre 2026 (heure italienne)<\/strong><\/p>\n<p>Pour formaliser l\u2019inscription, les candidats doivent se pr\u00e9senter aupr\u00e8s du si\u00e9g\u00e9 de cet Institut (2 bis, Avenue Ahmed El Yazidi Quartier Hassan \u2013 Rabat ) munis des pi\u00e8ces suivantes\u00a0:<\/p>\n<ul>\n<li>CINE en original ou titre de s\u00e9jour valable pour les \u00e9trangers r\u00e9sidents au Maroc;<\/li>\n<li>Formulaire dument compl\u00e9t\u00e9 en lettres majuscules (il sera remis directement en main propre);<\/li>\n<li>Une fois l\u2019inscription r\u00e9serv\u00e9e et apr\u00e8s avoir re\u00e7u confirmation de l\u2019administration concernant la disponibilit\u00e9 de l\u2019activation de la session, il est n\u00e9cessaire d\u2019effectuer le paiement demand\u00e9 en MAD (motif: examens CILS) aupr\u00e8s d\u2019une agence du Cr\u00e9dit du Maroc au profit de l\u2019I<strong>nstitut Culturel Italien de Rabat (Banque : CREDIT DU MAROC, RIB : 021 810 0000 035 005 40 110 7 40)\u00a0<\/strong>en indiquant vos pr\u00e9nom et nom et votre num\u00e9ro CIN;<\/li>\n<li>Une fois le paiement demand\u00e9 effectu\u00e9, il est n\u00e9cessaire de remettre l\u2019original du re\u00e7u de paiement des frais d\u2019inscription d\u2019examen ;<\/li>\n<li>Apr\u00e8s v\u00e9rification de la r\u00e9gularit\u00e9 du paiement, un re\u00e7u d\u2019inscription vous sera d\u00e9livr\u00e9 selon la date de la session choisie.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Certification d\u2019Italien comme langue \u00e9trang\u00e8re Les certifications de la langue Italienne sont des titres officiels qui attestent et certifient le niveau de la langue Italienne en tant que langue \u00e9trang\u00e8re selon les niveaux d\u00e9finis par le Cadre Europ\u00e9en Commune de R\u00e9f\u00e9rence pour les langues (Common European Framework of Reference for Languages). Ils sont destin\u00e9s \u00e0 [&hellip;]","protected":false},"author":1,"featured_media":4841,"parent":104,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-107","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":8,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/107\/revisions"}],"predecessor-version":[{"id":8441,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/107\/revisions\/8441"}],"up":[{"embeddable":true,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/media\/4841"}],"wp:attachment":[{"href":"https:\/\/iicrabat.esteri.it\/fr\/wp-json\/wp\/v2\/media?parent=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}